{"id":1641,"date":"2024-09-19T14:50:58","date_gmt":"2024-09-19T14:50:58","guid":{"rendered":"https:\/\/spectrals.ch\/sebastien\/?page_id=1641"},"modified":"2026-07-21T09:02:52","modified_gmt":"2026-07-21T09:02:52","slug":"specimens","status":"publish","type":"page","link":"https:\/\/spectrals.ch\/sebastien\/specimens\/","title":{"rendered":"SP\u00c9CIMENS"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||-43px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-15px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb-15px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dsm_masonry_gallery gallery_ids=\u00a0\u00bb1935,1936,1404,1403,1401,1483,1402,1570,1647,1571,1568,1646&Prime; dsm_sort_images=\u00a0\u00bboff\u00a0\u00bb columns=\u00a0\u00bb2&Prime; gutter=\u00a0\u00bb10&Prime; use_overlay=\u00a0\u00bbon\u00a0\u00bb overlay_title=\u00a0\u00bboff\u00a0\u00bb overlay_caption=\u00a0\u00bboff\u00a0\u00bb overlay_description=\u00a0\u00bboff\u00a0\u00bb use_lightbox=\u00a0\u00bbon\u00a0\u00bb lightbox_title=\u00a0\u00bboff\u00a0\u00bb lightbox_caption=\u00a0\u00bboff\u00a0\u00bb overlay_color=\u00a0\u00bbrgba(255,255,255,0.7)\u00a0\u00bb columns_tablet=\u00a0\u00bb2&Prime; columns_phone=\u00a0\u00bb2&Prime; columns_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/dsm_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"et_pb_module dsm_masonry_gallery dsm_masonry_gallery_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-gallery grid\" data-lightbox=\"true\" data-horizontalorder=\"true\">\n                <div class=\"grid-sizer\"><\/div><div class=\"gutter-sizer\"><\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_specimens_01\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_01-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_02.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_02.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_02.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_specimens_02\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_02.jpg 819w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2026\/07\/spectrals_sebastien_bridot_nowhereland_specimens_02-480x600.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 819px, 100vw\" width=\"819\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_01\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01-980x1232.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_01-480x603.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1287\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_06\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_06-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_04\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_04-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_02\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02-980x1231.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/04\/spectrals_sebastien_bridot_nowhereland_still_life_02-480x603.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1286\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_03\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03-980x1231.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/03\/spectrals_sebastien_bridot_nowhereland_still_life_03-480x603.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1286\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09.jpg\" title=\"spectrals_sebastien_bridot_mont_analogue_09\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_09-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_07\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_07-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_03.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_03.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_03.jpg\" title=\"spectrals_sebastien_bridot_mont_analogue_03\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_03.jpg 800w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_03-480x602.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" width=\"800\" height=\"1004\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04.jpg\" title=\"spectrals_sebastien_bridot_mont_analogue_04\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_mont_analogue_04-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div><div class=\"grid-item\">\n                    <a href=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05.jpg\"   data-mfp-src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05.jpg\">\n                        <div class=\"et_pb_image_wrap\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05.jpg\" title=\"spectrals_sebastien_bridot_nowhereland_still_life_05\" alt=\"\" class=\"dsm-skip-lazyload\" srcset=\"https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05.jpg 1024w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05-980x980.jpg 980w, https:\/\/spectrals.ch\/sebastien\/wp-content\/uploads\/2024\/09\/spectrals_sebastien_bridot_nowhereland_still_life_05-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" width=\"1024\" height=\"1024\" \/>\n                            <span class=\"et_overlay dsm-overlay\">\n                        <div class=\"dsm-overlay-inner\">\n                            \n                            \n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/span>\n                        <\/div>\n                    <\/a>\n                <\/div>\n             <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-1641","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/pages\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":5,"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/pages\/1641\/revisions"}],"predecessor-version":[{"id":1939,"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/pages\/1641\/revisions\/1939"}],"wp:attachment":[{"href":"https:\/\/spectrals.ch\/sebastien\/wp-json\/wp\/v2\/media?parent=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}